{"id":1027,"date":"2023-11-01T15:23:58","date_gmt":"2023-11-01T19:23:58","guid":{"rendered":"http:\/\/comisiondeportivatouring.com\/site\/?p=1027"},"modified":"2023-11-01T15:23:58","modified_gmt":"2023-11-01T19:23:58","slug":"alex-popow-jr-en-los-sudamericanos-esports","status":"publish","type":"post","link":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/2023\/11\/01\/alex-popow-jr-en-los-sudamericanos-esports\/","title":{"rendered":"ALEX POPOW Jr EN LOS SUDAMERICANOS eSPORTS"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"size-medium wp-image-1028 alignleft\" src=\"http:\/\/comisiondeportivatouring.com\/site\/wp-content\/uploads\/2023\/11\/AlexPopowP_H-300x191.jpeg\" alt=\"\" width=\"300\" height=\"191\" srcset=\"https:\/\/comisiondeportivatouring.com\/site\/wp-content\/uploads\/2023\/11\/AlexPopowP_H-300x191.jpeg 300w, https:\/\/comisiondeportivatouring.com\/site\/wp-content\/uploads\/2023\/11\/AlexPopowP_H-1024x652.jpeg 1024w, https:\/\/comisiondeportivatouring.com\/site\/wp-content\/uploads\/2023\/11\/AlexPopowP_H-768x489.jpeg 768w, https:\/\/comisiondeportivatouring.com\/site\/wp-content\/uploads\/2023\/11\/AlexPopowP_H.jpeg 1467w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> &#8211; El adolescente Alex Popow Jr ser\u00e1 el representante de Venezuela en la primera edici\u00f3n del Suramericano de Automovilismo eRacing que se disputar\u00e1 este jueves 2 de noviembre en Sao Paulo, Brasil, dentro de las actividades de contorno del Gran Premio de F\u00f3rmula 1 a desarrollarse en el circuito de Interlagos Jos\u00e9 Carlos Pace.<\/p>\n<p>&#8211; Alex Popow Jr o III, es hijo del multicampe\u00f3n de automovilismo venezolano del mismo nombre y nieto de Alejandro, especialista del rally venezolano en los a\u00f1os 70 y 80. Residenciado en Florida, Estados Unidos donde este a\u00f1o ha conseguido triunfar en distintas pruebas (reales, es decir, no virtuales) de monoplazas disputadas en el trazado de Homestead, Popow Jr clasific\u00f3 para esta edici\u00f3n del certamen digital al apoderarse del cuarto mejor registro en las eliminatorias regionales desarrolladas sobre el dibujo de Laguna Seca, California, mientras las tres mejores marcas se las llevaron los pilotos brasile\u00f1os.<\/p>\n<p>Podr\u00e1n seguir esta participaci\u00f3n en vivo a trav\u00e9s de YouTube en el siguiente link (v\u00ednculo), ma\u00f1ana jueves 2 de noviembre a las 18:30\u00a0 <a href=\"https:\/\/www.youtube.com\/live\/qojGtNzSLs4?si=7o0bajLDwYlvmRZX\">https:\/\/www.youtube.com\/live\/qojGtNzSLs4?si=7o0bajLDwYlvmRZX<\/a><\/p>\n<p>&nbsp;<\/p>\n<h4>Prensa Prototipos Octavio Estrada \/ Prensa TACV Carlos Suchanek<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; El adolescente Alex Popow Jr ser\u00e1 el representante de Venezuela en la primera edici\u00f3n del Suramericano de Automovilismo eRacing<\/p>\n","protected":false},"author":1,"featured_media":1029,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[10],"_links":{"self":[{"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/posts\/1027"}],"collection":[{"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/comments?post=1027"}],"version-history":[{"count":1,"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/posts\/1027\/revisions"}],"predecessor-version":[{"id":1030,"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/posts\/1027\/revisions\/1030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/media\/1029"}],"wp:attachment":[{"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/media?parent=1027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/categories?post=1027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/tags?post=1027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}