{"id":794,"date":"2021-07-15T19:30:41","date_gmt":"2021-07-15T23:30:41","guid":{"rendered":"http:\/\/comisiondeportivatouring.com\/site\/?p=794"},"modified":"2021-07-15T20:05:10","modified_gmt":"2021-07-16T00:05:10","slug":"la-f1-anuncia-un-plan-de-becas-y-practicas-para-aumentar-la-diversidad","status":"publish","type":"post","link":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/2021\/07\/15\/la-f1-anuncia-un-plan-de-becas-y-practicas-para-aumentar-la-diversidad\/","title":{"rendered":"LA F1 ANUNCIA UN PLAN DE BECAS Y PR\u00c1CTICAS PARA AUMENTAR LA DIVERSIDAD"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"http:\/\/comisiondeportivatouring.com\/site\/wp-content\/uploads\/2021\/07\/FIACURSOS01.jpg\" alt=\"\" class=\"wp-image-800\" width=\"300\" height=\"200\" srcset=\"https:\/\/comisiondeportivatouring.com\/site\/wp-content\/uploads\/2021\/07\/FIACURSOS01.jpg 600w, https:\/\/comisiondeportivatouring.com\/site\/wp-content\/uploads\/2021\/07\/FIACURSOS01-300x200.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p><strong>Luke Smith &#8211; motorsport.com<\/strong><br><\/p>\n\n\n\n<p>La F\u00f3rmula 1 ha desvelado un nuevo programa de becas, pr\u00e1cticas y aprendizaje orientado a los grupos menos representados para mejorar la diversidad en toda la industria.<\/p>\n\n\n\n<p><strong>La F1 anuncia un plan de becas y pr\u00e1cticas para aumentar la diversidad<\/strong><\/p>\n\n\n\n<p>Como parte de su iniciativa <strong>We Race As One<\/strong>, la F1 anunci\u00f3 en junio de 2020 que crear\u00eda una fundaci\u00f3n para ayudar a financiar becas y matr\u00edculas para estudiantes de or\u00edgenes diversos, incluyendo una donaci\u00f3n personal de un mill\u00f3n de d\u00f3lares por parte del presidente ejecutivo de la F1, Chase Carey.<\/p>\n\n\n\n<p>Todo esto lleg\u00f3 despu\u00e9s de que Lewis Hamilton presionara para que la F1 fuera m\u00e1s diversa, incluyendo la creaci\u00f3n de la Comisi\u00f3n Hamilton para identificar por qu\u00e9 las personas de raza negra y otros grupos \u00e9tnicos minoritarios est\u00e1n poco representados en el campeonato.<\/p>\n\n\n\n<p>El informe de la Comisi\u00f3n Hamilton se hizo p\u00fablico este martes y concluy\u00f3 que s\u00f3lo el 1% de los empleados de la F1 son de raza negra.<\/p>\n\n\n\n<p>La F1 ya avanz\u00f3 en marzo sus planes para ofrecer m\u00e1s oportunidades a trav\u00e9s de su programa de becas y ahora ha explicado los detalles de las medidas que tomar\u00e1.<\/p>\n\n\n\n<p>Se van a ofrecer 10 becas de ingenier\u00eda de F\u00f3rmula 1 a los estudiantes de \u00abgrupos poco representados, como las minor\u00edas \u00e9tnicas, las mujeres y las personas de entornos desfavorecidos\u00bb, que cubrir\u00e1n el coste total de la matr\u00edcula y los gastos de alojamiento.<\/p>\n\n\n\n<p>Los 10 equipos de la F1 se han comprometido a ofrecer oportunidades laborales a un becario durante su estancia en la universidad, en instituciones asociadas que se encuentran en todo el Reino Unido e Italia \u2013la Universidad de Cambridge (1 becario), la Universidad de Coventry (1), la Universidad Metropolitana de Manchester (1), La Universidad del Motor de Emilia-Romagna MUNER (3), la Universidad de Oxford (2) y la Universidad de Strathclyde (1)\u2013.<\/p>\n\n\n\n<p>El Programa de aprendizaje de la F\u00f3rmula 1 permitir\u00e1 \u00abcolocar a dos becarios de larga duraci\u00f3n procedentes de grupos poco representados en nuestro campeonato en 2021. Los becarios comenzar\u00e1n en septiembre y se centrar\u00e1n en ingenier\u00eda mec\u00e1nica\u00bb.<\/p>\n\n\n\n<p>Por \u00faltimo, el Programa de Pr\u00e1cticas de la F\u00f3rmula 1 ofrecer\u00e1 este a\u00f1o a seis becarios de grupos poco representados funciones en la F1 en puestos de trabajo a corto y largo plazo, dos de los cuales ya han sido asignados en los equipos de automovilismo y marketing de la F1.<\/p>\n\n\n\n<p>El comunicado de la F1 dice que los cuatro restantes \u00abser\u00e1n contratados en las pr\u00f3ximas semanas a trav\u00e9s de m\u00faltiples socios de D&amp;I (diversidad e inclusi\u00f3n), incluyendo: BCOMS (licenciados en comercio), para entusiastas de los medios de comunicaci\u00f3n deportivos con talento que buscan desarrollar su carrera; Driven By Diversity, cuya misi\u00f3n es educar a las personas y organizaciones sobre el valor de la diversidad y la inclusi\u00f3n en el deporte del motor; y otras iniciativas que forman y nutren a los j\u00f3venes de grupos subrepresentados o con oportunidades educativas o de empleo limitadas\u00bb.<\/p>\n\n\n\n<p>\u00abLa F\u00f3rmula 1 es un deporte global con aficionados en todo el mundo\u00bb, dijo el director general y presidente de la F1, Stefano Domenicali.<\/p>\n\n\n\n<p>\u00abQueremos ser tan diversos como nuestra base de fans y por eso estamos tomando medidas para garantizar que las personas con talento de los grupos subrepresentados tengan las mejores oportunidades para entrar y desarrollar una fant\u00e1stica carrera en este incre\u00edble deporte\u00bb.<\/p>\n\n\n\n<p>\u00abEstoy encantado de anunciar que los becarios, aprendices y pasantes tendr\u00e1n la oportunidad de cumplir sus sue\u00f1os en la F\u00f3rmula 1 y s\u00e9 que tienen un futuro incre\u00edble por delante. Quiero dar las gracias especialmente a Chase, cuya generosa donaci\u00f3n financia las diez becas\u00bb.<\/p>\n\n\n\n<p>\u00abLa plataforma <strong>#WeRaceAsOne<\/strong> es nuestro compromiso para hacer un cambio real y muestra nuestro reconocimiento de que sabemos que debemos hacer una contribuci\u00f3n positiva al mundo en el que vivimos. Todos los equipos est\u00e1n comprometidos con esto y el trabajo de la Comisi\u00f3n Hamilton muestra la dedicaci\u00f3n para abordar estos temas en toda la F\u00f3rmula 1&#8243;.<\/p>\n\n\n\n<p>\u00abNuestro enfoque se centra en la Diversidad e Inclusi\u00f3n, la Sostenibilidad y la Comunidad y seguiremos impulsando nuestros planes para ser m\u00e1s diversos, m\u00e1s sostenibles y dejar un impacto positivo duradero en los pa\u00edses y comunidades que visitamos.<\/p>\n\n\n\n<p>\u00abSabemos que debemos seguir avanzando en estos temas y todo el campeonato est\u00e1 unido para hacerlo en los pr\u00f3ximos meses y a\u00f1os\u00bb.<br><br><br><strong>Luke Smith &#8211; motorsport.com<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luke Smith &#8211; motorsport.com La F\u00f3rmula 1 ha desvelado un nuevo programa de becas, pr\u00e1cticas y aprendizaje orientado a los<\/p>\n","protected":false},"author":1,"featured_media":801,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[10],"_links":{"self":[{"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/posts\/794"}],"collection":[{"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/comments?post=794"}],"version-history":[{"count":6,"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/posts\/794\/revisions"}],"predecessor-version":[{"id":806,"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/posts\/794\/revisions\/806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/media\/801"}],"wp:attachment":[{"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/media?parent=794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/categories?post=794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comisiondeportivatouring.com\/site\/index.php\/wp-json\/wp\/v2\/tags?post=794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}